{"id":822,"date":"2022-03-28T02:59:28","date_gmt":"2022-03-28T02:59:28","guid":{"rendered":"https:\/\/affiv.com\/?p=822"},"modified":"2022-03-28T02:59:36","modified_gmt":"2022-03-28T02:59:36","slug":"what-is-dae-file-format-how-to-open-and-convert-dae-file","status":"publish","type":"post","link":"https:\/\/affiv.com\/pt\/o-que-e-formato-de-arquivo-dae-como-abrir-e-converter-arquivo-dae\/","title":{"rendered":"O que \u00e9 o formato de arquivo DAE? Como abrir e converter arquivo DAE?"},"content":{"rendered":"<p>O arquivo DAE \u00e9 uma abrevia\u00e7\u00e3o de Digital Asset Exchange File, que \u00e9 usado por v\u00e1rios programas gr\u00e1ficos para trocar dados digitais, imagens, texturas, modelos 3D, etc. <\/p>\n\n\n\n<p>Os arquivos DAE s\u00e3o baseados no formato XML COLLADA, e DAE tamb\u00e9m \u00e9 uma abrevia\u00e7\u00e3o de termos t\u00e9cnicos, como gabinete de matriz de disco ou mecanismo de \u00e1udio digital.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-src=\"https:\/\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251-1024x576.jpg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"O que \u00e9 arquivo DAE\" class=\"wp-image-823 lazyload\"\/><noscript><img decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251-1024x576.jpg?resize=900%2C506&#038;ssl=1\" alt=\"O que \u00e9 arquivo DAE\" class=\"wp-image-823\" srcset=\"https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 900px) 100vw, 900px\" data-recalc-dims=\"1\" \/><\/noscript><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Como fa\u00e7o para abrir um arquivo DAE?<\/h2>\n\n\n\n<p>Arquivos DAE podem ser importados para Adobe Photoshop, <a href=\"https:\/\/www.sketchup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">1TP168UP<\/a>, <a href=\"https:\/\/www.chiefarchitect.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Chief Architect<\/a>, <a href=\"https:\/\/www.daz3d.com\/daz_studio\" target=\"_blank\" rel=\"noreferrer noopener\">DAZ Studio<\/a>, <a href=\"https:\/\/www.cheetah3d.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cheetah3D<\/a>, <a href=\"https:\/\/www.maxon.net\/en\/products\/cinema-4d\/overview\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cinema 4D<\/a>, <a href=\"https:\/\/www.foundry.com\/products\/modo\" target=\"_blank\" rel=\"noreferrer noopener\">MODO<\/a>, bem como Autodesk AutoCAD, 3ds Max e <a href=\"https:\/\/www.autodesk.com\/products\/maya\/overview\" target=\"_blank\" rel=\"noreferrer noopener\">Maya<\/a>, e outros aplicativos gratuitos, como o <a href=\"https:\/\/www.blender.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blender<\/a>.<\/p>\n\n\n\n<p>Esses programas requerem a instala\u00e7\u00e3o do <a href=\"https:\/\/sourceforge.net\/projects\/colladamaya\/\" target=\"_blank\" rel=\"noreferrer noopener\">COLLADA<\/a> plug-in para Maya e 3ds Max, e Blender tamb\u00e9m requer a instala\u00e7\u00e3o do <a href=\"https:\/\/sourceforge.net\/projects\/colladablender\/\" target=\"_blank\" rel=\"noreferrer noopener\">COLLADA<\/a> plug-in para abrir arquivos DAE.<\/p>\n\n\n\n<p>Os usu\u00e1rios do Linux podem usar <a href=\"http:\/\/www.glc-player.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">GLC Player<\/a> para abrir arquivos DAE. Os usu\u00e1rios do macOS podem usar o Apple Preview para abrir arquivos DAE. Alguns arquivos DAE tamb\u00e9m podem ser abertos com o Esko gr\u00e1tis <a href=\"https:\/\/www.esko.com\/en\/Support\/DownloadsAndLicenses\/free-software#Viewers\" target=\"_blank\" rel=\"noreferrer noopener\">Studio Viewer<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/clara.io\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clara.io<\/a> \u00e9 uma maneira f\u00e1cil de visualizar arquivos DAE em um navegador da Web, portanto, voc\u00ea n\u00e3o precisa baixar nenhum software e \u00e9 gratuito para uso.<\/p>\n\n\n\n<p>Programas que podem abrir arquivos de texto tamb\u00e9m devem ser capazes de abrir DAEs, mas isso n\u00e3o \u00e9 ideal porque exibe apenas texto, e a melhor maneira de visualizar arquivos 3D DAE \u00e9 usar um visualizador profissional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como converter arquivo DAE?<\/h2>\n\n\n\n<p>A maneira mais f\u00e1cil de converter o formato DAE \u00e9 usar um <a href=\"http:\/\/www.greentoken.de\/onlineconv\/\" target=\"_blank\" rel=\"noreferrer noopener\">ferramenta de convers\u00e3o online<\/a> para fazer upload de arquivos DAE para o site e, em seguida, escolha diferentes formatos, como OBJ, 3DS, STL, PLY, etc.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.autodesk.com\/developer-network\/platform-technologies\/fbx-converter-archives\" target=\"_blank\" rel=\"noreferrer noopener\">Conversor FBX<\/a> \u00e9 uma ferramenta gratuita da Autodesk para Windows e macOS que converte arquivos DAE para FBX e suporta v\u00e1rias vers\u00f5es do formato FBX.<\/p>\n\n\n\n<p>Importando arquivos DAE para <a href=\"https:\/\/www.sketchup.com\/products\/sketchup-pro\" target=\"_blank\" rel=\"noreferrer noopener\">SketchUp Pro<\/a>, o programa pode exportar modelos 3D para DWG, DXF e v\u00e1rios outros formatos semelhantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ainda n\u00e3o consegue abrir o arquivo DAE?<\/h2>\n\n\n\n<p>Se o arquivo DAE n\u00e3o for executado sem problemas de acordo com todos os m\u00e9todos descritos acima, provavelmente \u00e9 um arquivo em outro formato. \u00c0s vezes \u00e9 f\u00e1cil interpretar mal as extens\u00f5es de arquivo. Algumas extens\u00f5es de arquivo podem ser semelhantes.<\/p>\n\n\n\n<p>Por exemplo, um arquivo DAE \u00e9 muito semelhante a um arquivo DAR, DAA, DAT ou DAO (Disk at Once CD\/DVD Image), mas n\u00e3o est\u00e1 relacionado ao DAE.<\/p>\n\n\n\n<p>\u00c9 prov\u00e1vel que o ADE tamb\u00e9m seja confundido com o DAE, que \u00e9 uma extens\u00e3o de projeto do Access que s\u00f3 pode ser usada em <a href=\"https:\/\/www.microsoft.com\/en-us\/microsoft-365\/access\" target=\"_blank\" rel=\"noreferrer noopener\">Microsoft Access<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>O arquivo DAE \u00e9 uma abrevia\u00e7\u00e3o de Digital Asset Exchange File, que \u00e9 usado por v\u00e1rios programas gr\u00e1ficos para trocar dados digitais, imagens, texturas, modelos 3D, etc. <\/p>","protected":false},"author":1,"featured_media":823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[166],"tags":[175],"class_list":["post-822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to","tag-dae"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/affiv.com\/wp-content\/uploads\/2022\/03\/My-project-2022-03-24T174000.251.jpg?fit=1280%2C720&ssl=1","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/posts\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/comments?post=822"}],"version-history":[{"count":2,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/posts\/822\/revisions"}],"predecessor-version":[{"id":827,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/posts\/822\/revisions\/827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/media\/823"}],"wp:attachment":[{"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/media?parent=822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/categories?post=822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/affiv.com\/pt\/wp-json\/wp\/v2\/tags?post=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}